{"id":4175,"date":"2022-03-24T20:26:15","date_gmt":"2022-03-24T20:26:15","guid":{"rendered":"https:\/\/www.keybak.amicalementgeorge.com\/?post_type=product&#038;p=4175"},"modified":"2026-06-01T09:15:26","modified_gmt":"2026-06-01T09:15:26","slug":"trabalho-de-base-1","status":"publish","type":"product","link":"https:\/\/key-bak.fr\/pt\/produit\/key-bak-work-1\/","title":{"rendered":"Key-Bak TRABALHO 1"},"content":{"rendered":"<p>Bobina retr\u00e1til \u00abKeyBak\u00ab\u00a0<strong>TRABALHO 1<\/strong> \u00bb tornou-se a ferramenta indispens\u00e1vel para proteger pequenos objetos (chaves de aperto, manuais de instru\u00e7\u00f5es, listas de verifica\u00e7\u00e3o, etc.) gra\u00e7as ao anel fixado num cabo de Kevlar de 120 cm.<\/p>\n<h2>Design robusto e duradouro<\/h2>\n<p>Fabricado nos EUA, o enrolador retr\u00e1til industrial Key-Bak foi concebido para durar uma vida inteira. Equipado com uma mola de a\u00e7o inoxid\u00e1vel de alta qualidade, este carreto \u00e9 reconhecido como o mais fi\u00e1vel do mundo.<\/p>\n<h2>Caixa atractiva e duradoura<\/h2>\n<p>A caixa em a\u00e7o cromado texturizado, com 5 cm de di\u00e2metro soldada a uma base met\u00e1lica de 7 cm que pode fixar \u00e0 sua m\u00e1quina ou parede, garante robustez e est\u00e9tica.<\/p>\n<h2>Capacidade e for\u00e7a de retra\u00e7\u00e3o<\/h2>\n<p>Com uma for\u00e7a de retra\u00e7\u00e3o de 225 gramas, este enrolador pode suportar pequenas ferramentas ou o equivalente em peso de 15 chaves grandes.<\/p>\n<h2>Acess\u00f3rios inclu\u00eddos e montagem f\u00e1cil<\/h2>\n<p>O enrolador possui um anel zincado para maior durabilidade e versatilidade. Um suporte de a\u00e7o cromado permite uma montagem f\u00e1cil em qualquer superf\u00edcie utilizando duas fixa\u00e7\u00f5es.<\/p>\n<h2>Versatilidade excecional<\/h2>\n<p>Ideal para profissionais da ind\u00fastria de servi\u00e7os, seguran\u00e7a, casinos e muito mais, o KeyBak Work 1 \u00e9 perfeito para guardar chaves, pequenas ferramentas, lanternas e outros equipamentos essenciais.<\/p>\n<h2>Garantia e fiabilidade<\/h2>\n<p>Cada porta-chaves KEY-BAK \u00e9 suportado por uma garantia limitada de um ano e uma pol\u00edtica de repara\u00e7\u00e3o vital\u00edcia, refletindo o nosso compromisso com a qualidade e a satisfa\u00e7\u00e3o do cliente. Desde a sua funda\u00e7\u00e3o em 1948, a KEY-BAK continua a fornecer solu\u00e7\u00f5es fi\u00e1veis e pr\u00e1ticas para todos aqueles que necessitam de acesso seguro e conveniente \u00e0s suas ferramentas e chaves.<\/p>","protected":false},"excerpt":{"rendered":"<h3>Para uso industrial<\/h3>\n<p>O KeyBak WORK 1 \u00e9 uma ferramenta indispens\u00e1vel para utiliza\u00e7\u00e3o industrial, gra\u00e7as ao seu cabo de a\u00e7o inoxid\u00e1vel.<\/p>\n<h3>Carater\u00edsticas<\/h3>\n<ul>\n<li>For\u00e7a de contra\u00e7\u00e3o de 225 gramas<\/li>\n<li>Cabo Kevlar ultra-resistente de 120 cm<\/li>\n<li>Suporte met\u00e1lico de 7 cm<\/li>\n<li>Conjunto de molas em a\u00e7o inoxid\u00e1vel numa caixa de 5 cm em a\u00e7o inoxid\u00e1vel<\/li>\n<li>Anel de a\u00e7o temperado resistente \u00e0 corros\u00e3o de 2,5 cm<\/li>\n<li>Testado para durar 1 milh\u00e3o de impress\u00f5es<\/li>\n<li>Fabricado nos EUA<\/li>\n<\/ul>","protected":false},"featured_media":4725,"template":"","meta":[],"product_brand":[],"product_cat":[68,28],"product_tag":[],"class_list":["post-4175","product","type-product","status-publish","has-post-thumbnail","product_cat-industrie","product_cat-key-bak-speciaux","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/key-bak.fr\/pt\/wp-json\/wp\/v2\/product\/4175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/key-bak.fr\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/key-bak.fr\/pt\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/key-bak.fr\/pt\/wp-json\/wp\/v2\/product\/4175\/revisions"}],"predecessor-version":[{"id":9056,"href":"https:\/\/key-bak.fr\/pt\/wp-json\/wp\/v2\/product\/4175\/revisions\/9056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/key-bak.fr\/pt\/wp-json\/wp\/v2\/media\/4725"}],"wp:attachment":[{"href":"https:\/\/key-bak.fr\/pt\/wp-json\/wp\/v2\/media?parent=4175"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/key-bak.fr\/pt\/wp-json\/wp\/v2\/product_brand?post=4175"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/key-bak.fr\/pt\/wp-json\/wp\/v2\/product_cat?post=4175"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/key-bak.fr\/pt\/wp-json\/wp\/v2\/product_tag?post=4175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}